{"id":146,"count":1,"description":"","link":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","name":"2-3 ans","slug":"2-3-ans","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2-3 ans Archives - O-Volt Blainville<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2-3 ans Archives - O-Volt Blainville\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"O-Volt Blainville\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/product-category\\\/2-3-ans\\\/\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/product-category\\\/2-3-ans\\\/\",\"name\":\"2-3 ans Archives - O-Volt Blainville\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/product-category\\\/2-3-ans\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/product-category\\\/2-3-ans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2-3 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/#website\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/\",\"name\":\"O-Volt Blainville\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltblainville\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2-3 ans Archives - O-Volt Blainville","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","og_locale":"fr_CA","og_type":"article","og_title":"2-3 ans Archives - O-Volt Blainville","og_url":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","og_site_name":"O-Volt Blainville","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","url":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","name":"2-3 ans Archives - O-Volt Blainville","isPartOf":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/#website"},"breadcrumb":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/"},{"@type":"ListItem","position":2,"name":"2-3 ans"}]},{"@type":"WebSite","@id":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/#website","url":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/","name":"O-Volt Blainville","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"cat_url":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/product-category\/2-3-ans\/","_links":{"self":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/wp-json\/wp\/v2\/product_cat\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltblainville\/wp-json\/wp\/v2\/product?product_cat=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}