{"id":79,"count":2,"description":"","link":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","name":"Les Ninjas - Cours d'agilit\u00e9","slug":"agilite","taxonomy":"product_cat","parent":37,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Ninjas - Cours d&#039;agilit\u00e9 | O-Volt LaSalle<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre s\u00e9lection de cours d&#039;agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Ninjas - Cours d&#039;agilit\u00e9 | O-Volt LaSalle\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre s\u00e9lection de cours d&#039;agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/\" \/>\n<meta property=\"og:site_name\" content=\"O-volt Lasalle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/product-category\\\/cours\\\/agilite\\\/\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/product-category\\\/cours\\\/agilite\\\/\",\"name\":\"Les Ninjas - Cours d'agilit\u00e9 | O-Volt LaSalle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/#website\"},\"description\":\"D\u00e9couvrez notre s\u00e9lection de cours d'agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/product-category\\\/cours\\\/agilite\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/product-category\\\/cours\\\/agilite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cours\",\"item\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/product-category\\\/cours\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Ninjas - Cours d'agilit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/#website\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/\",\"name\":\"O-volt Lasalle\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltlasalle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Ninjas - Cours d'agilit\u00e9 | O-Volt LaSalle","description":"D\u00e9couvrez notre s\u00e9lection de cours d'agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","og_locale":"fr_CA","og_type":"article","og_title":"Les Ninjas - Cours d'agilit\u00e9 | O-Volt LaSalle","og_description":"D\u00e9couvrez notre s\u00e9lection de cours d'agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.","og_url":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","og_site_name":"O-volt Lasalle","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","url":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","name":"Les Ninjas - Cours d'agilit\u00e9 | O-Volt LaSalle","isPartOf":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/#website"},"description":"D\u00e9couvrez notre s\u00e9lection de cours d'agilit\u00e9 de type ninja warrior - cat\u00e9gorie pour les enfants de 6 \u00e0 9 ans ou pour les jeunes de 10 \u00e0 13 ans.","breadcrumb":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/"},{"@type":"ListItem","position":2,"name":"Cours","item":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/"},{"@type":"ListItem","position":3,"name":"Les Ninjas - Cours d'agilit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/#website","url":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/","name":"O-volt Lasalle","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"cat_url":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/product-category\/cours\/agilite\/","_links":{"self":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/wp-json\/wp\/v2\/product_cat\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/wp-json\/wp\/v2\/product_cat\/37"}],"wp:post_type":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltlasalle\/wp-json\/wp\/v2\/product?product_cat=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}