{"id":1949,"date":"2019-03-06T22:38:00","date_gmt":"2019-03-07T03:38:00","guid":{"rendered":"https:\/\/o-volt.ca\/?post_type=product&#038;p=1949"},"modified":"2026-04-06T14:26:52","modified_gmt":"2026-04-06T18:26:52","slug":"les-baranis","status":"publish","type":"product","link":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/","title":{"rendered":"Les Baranis &#8211; Cours de trampoline avanc\u00e9 pour les enfants"},"content":{"rendered":"<p><strong>C\u2019EST QUOI :\u00a0<\/strong>Cours de trampoline avanc\u00e9<br \/>\n<strong>\u00c2GE :<\/strong>\u00a0\u00e0 partir de 6 ans<br \/>\n<strong>GROUPE :<\/strong>\u00a08 personnes maximum<br \/>\n<strong>HORAIRE : <b>D\u00e9but des cours dans la semaine du 20 avril 2026<\/b><\/strong><\/p>\n<p>Mardi 18 h15 \u00e0 19 h 45<\/p>\n<p>Jeudi 19h15h \u00e0 20h45<\/p>\n<p>Dur\u00e9e 8 semaines<\/p>\n<p><strong>PRIX :<\/strong> 189$+tx<\/p>\n<p><strong>DESCRIPTION DU COURS :\u00a0<\/strong>Selon les objectifs des participants, ce cours vise l\u2019enseignement des vrilles et des saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.<\/p>\n<p><strong>PR\u00c9-REQUIS :<\/strong>\u00a0Cours interm\u00e9diaire de trampoline (Saltos niveau 2) ou \u00e9valuation lors des journ\u00e9es portes ouvertes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trampoline Avanc\u00e9 (6 \u00e0 15 ans)<\/p>\n","protected":false},"featured_media":104111,"template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0"},"product_brand":[],"product_cat":[73,71],"product_tag":[117,59],"class_list":{"0":"post-1949","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-6-a-15-ans","7":"product_cat-cours","8":"product_tag-jeune","9":"product_tag-trampoline-fr","11":"entry","12":"has-media","14":"first","15":"outofstock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable","20":"col","21":"span_1_of_5","22":"owp-content-center","23":"owp-thumbs-layout-horizontal","24":"owp-btn-normal","25":"owp-tabs-layout-horizontal","26":"has-no-thumbnails","27":"circle-sale"},"exclude_global_add_ons":false,"addons":[{"name":"Pr\u00e9nom et nom de l'enfant:","type":"custom_text","position":0,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"only_letters","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1726671219},{"name":"date de naissance:","type":"datepicker","position":1,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1726671220},{"name":"No assurance maladie (sans espace)","type":"custom_text","position":2,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":true,"placeholder":"ABCD12345678","display":"select","restrictions_type":"only_letters_numbers","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":true,"min":"12","max":"12","options":[],"id":1726671221},{"name":"Diagnostic m\u00e9dical en cas d'urgence et autres \u00e9tats de sant\u00e9:","type":"custom_textarea","position":3,"required":false,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1726671224},{"name":"Contact en cas d'urgence","type":"custom_text","position":4,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"only_letters","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1726671222},{"name":"No T\u00e9l\u00e9phone en cas d'urgence","type":"custom_text","position":5,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":true,"placeholder":"111-222-3333","display":"select","restrictions_type":"only_numbers","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[],"id":1726671223},{"name":"Je comprends que le cours n\u2019est pas remboursable:","type":"checkbox","position":6,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[{"label":"OUI","price":"","price_type":"flat_fee","image":0,"visibility":true}],"id":1726671225},{"name":"La d\u00e9charge \u00e0 \u00e9t\u00e9 sign\u00e9e pour mon enfant:","type":"checkbox","position":7,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[{"label":"OUI","price":"","price_type":"flat_fee","image":0,"visibility":true}],"id":1726671226},{"name":"J'accepte de fournir les informations personelles ci-haut pour assurer le bon d\u00e9roulement du cours:","type":"checkbox","position":8,"required":true,"title_format":"label","default":"","description_enable":false,"description":"","placeholder_enable":false,"placeholder":"","display":"select","restrictions_type":"any_text","adjust_price":false,"price":"","price_type":"flat_fee","restrictions":false,"min":"0","max":"0","options":[{"label":"OUI","price":"","price_type":"flat_fee","image":0,"visibility":true}],"id":1726671227}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke<\/title>\n<meta name=\"description\" content=\"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke\" \/>\n<meta property=\"og:description\" content=\"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/\" \/>\n<meta property=\"og:site_name\" content=\"O-Volt Sherbrooke\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ovoltsherbrooke\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T18:26:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2025\/12\/17.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/\",\"name\":\"Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/17.png\",\"datePublished\":\"2019-03-07T03:38:00+00:00\",\"dateModified\":\"2026-04-06T18:26:52+00:00\",\"description\":\"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/17.png\",\"contentUrl\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/17.png\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/product\\\/les-baranis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les Baranis &#8211; Cours de trampoline avanc\u00e9 pour les enfants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#website\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/\",\"name\":\"O-Volt Sherbrooke\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#organization\",\"name\":\"O-Volt\",\"url\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ecom.o-possum.com\\\/ovoltsherbrooke\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/10\\\/O-solo-e1579028944818.png\",\"contentUrl\":\"https:\\\/\\\/ecom.o-possum.com\\\/ovoltsherbrooke\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/10\\\/O-solo-e1579028944818.png\",\"width\":300,\"height\":220,\"caption\":\"O-Volt\"},\"image\":{\"@id\":\"https:\\\/\\\/ecom.o-volt.ca\\\/ovoltsherbrooke\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ovoltsherbrooke\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke","description":"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke","og_description":"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.","og_url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/","og_site_name":"O-Volt Sherbrooke","article_publisher":"https:\/\/www.facebook.com\/ovoltsherbrooke\/","article_modified_time":"2026-04-06T18:26:52+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2025\/12\/17.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/","url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/","name":"Les Baranis - Cours de trampoline avanc\u00e9 | O-Volt Sherbrooke","isPartOf":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/#primaryimage"},"image":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/#primaryimage"},"thumbnailUrl":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2025\/12\/17.png","datePublished":"2019-03-07T03:38:00+00:00","dateModified":"2026-04-06T18:26:52+00:00","description":"Cours de trampoline avanc\u00e9 de 6 \u00e0 15 ans. Votre enfant apprendra les vrilles et les saltos sp\u00e9cialis\u00e9s, ainsi que le d\u00e9but des transitions entre les saltos.","breadcrumb":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/#primaryimage","url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2025\/12\/17.png","contentUrl":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2025\/12\/17.png","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/product\/les-baranis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/boutique\/"},{"@type":"ListItem","position":3,"name":"Les Baranis &#8211; Cours de trampoline avanc\u00e9 pour les enfants"}]},{"@type":"WebSite","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#website","url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/","name":"O-Volt Sherbrooke","description":"","publisher":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#organization","name":"O-Volt","url":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#\/schema\/logo\/image\/","url":"https:\/\/ecom.o-possum.com\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2019\/10\/O-solo-e1579028944818.png","contentUrl":"https:\/\/ecom.o-possum.com\/ovoltsherbrooke\/wp-content\/uploads\/sites\/7\/2019\/10\/O-solo-e1579028944818.png","width":300,"height":220,"caption":"O-Volt"},"image":{"@id":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ovoltsherbrooke\/"]}]}},"_links":{"self":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product\/1949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product\/1949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/media\/104111"}],"wp:attachment":[{"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/media?parent=1949"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product_brand?post=1949"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product_cat?post=1949"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ecom.o-volt.ca\/ovoltsherbrooke\/wp-json\/wp\/v2\/product_tag?post=1949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}